{"id":1698,"date":"2026-01-14T01:31:20","date_gmt":"2026-01-13T17:31:20","guid":{"rendered":"https:\/\/neosumk.com\/?p=1698"},"modified":"2026-02-13T18:55:43","modified_gmt":"2026-02-13T10:55:43","slug":"grades-of-magnets","status":"publish","type":"post","link":"https:\/\/osenc.com\/fr\/grades-of-magnets\/","title":{"rendered":"Grades des aimants"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Les aimants existent en diff\u00e9rentes qualit\u00e9s, en particulier les aimants en n\u00e9odyme (NdFeB). Le terme \u201cqualit\u00e9 d'aimant\u201d fait g\u00e9n\u00e9ralement r\u00e9f\u00e9rence au (BH)max ou \u00e0 l'\u00e9nergie maximale produite par le mat\u00e9riau, qui est une valeur cl\u00e9 pour comparer la force des qualit\u00e9s d'aimants au n\u00e9odyme. Si la qualit\u00e9 de l'aimant est un indicateur fiable de la r\u00e9sistance du mat\u00e9riau, elle n'\u00e9quivaut pas directement \u00e0 la force de traction, car d'autres facteurs tels que la g\u00e9om\u00e9trie et l'\u00e9tat de surface jouent un r\u00f4le important.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les applications pratiques, j'utilise la qualit\u00e9 comme premier filtre, puis j'affine le choix en fonction du volume de l'aimant, de l'entrefer, de l'\u00e9paisseur du rev\u00eatement et de l'\u00e9tat de la surface de l'acier. Un aimant de \u201chaute qualit\u00e9\u201d peut encore \u00eatre moins performant si les conditions de contact diff\u00e8rent des normes d'essai.<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9ponse rapide : Explication des degr\u00e9s d'aimantation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les aimants en n\u00e9odyme (NdFeB) sont class\u00e9s en fonction de leur (BH)max (produit \u00e9nerg\u00e9tique maximal, MGOe). Les qualit\u00e9s sup\u00e9rieures, telles que N42 ou <a href=\"\/fr\/n52-neodymium-magnets\/\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-theme-palette-12-color\">N52<\/mark><\/a>, La force de traction r\u00e9elle d\u00e9pend de facteurs tels que la g\u00e9om\u00e9trie, l'entrefer, l'\u00e9paisseur du rev\u00eatement et l'\u00e9tat de la surface de l'acier (par exemple, un acier plat et propre par rapport \u00e0 un acier mince ou peint).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous voyez des lettres suffixes comme <strong>M \/ H \/ SH \/ UH \/ EH \/ AH<\/strong>, il s'agit de <strong>degr\u00e9s de temp\u00e9rature de l'aimant<\/strong>. Ils augmentent principalement la r\u00e9sistance aux <strong>d\u00e9magn\u00e9tisation irr\u00e9versible<\/strong> dans des environnements chauds. D'apr\u00e8s mon exp\u00e9rience, la temp\u00e9rature est la raison #1 pour laquelle un aimant qui a pass\u00e9 avec succ\u00e8s les tests sur banc d'essai d\u00e9\u00e7oit ensuite dans un \u00e9quipement r\u00e9el, en particulier \u00e0 proximit\u00e9 de moteurs, de bo\u00eetiers ferm\u00e9s ou de tout ce qui s'imbibe de chaleur au fil du temps.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu'est-ce qu'une classe magn\u00e9tique ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les classes d'aimants sont une fa\u00e7on standard de d\u00e9crire la qualit\u00e9 de l'aimant. <strong>niveau de performance des mat\u00e9riaux<\/strong> d'un aimant. Pour les aimants au n\u00e9odyme (NdFeB), les nuances sont g\u00e9n\u00e9ralement \u00e9crites comme suit <strong>N<\/strong> + un nombre \u00e0 deux chiffres, parfois avec des lettres suppl\u00e9mentaires (par exemple : <strong>N42SH<\/strong>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un malentendu courant : <strong>\u201cN\u201d est une convention d'appellation utilis\u00e9e pour les nuances de NdFeB.<\/strong> sur le march\u00e9 (il ne s'agit pas d'une unit\u00e9 de physique), et le nombre est li\u00e9 \u00e0 la valeur de l'aimant. <strong>(BH)max<\/strong> g\u00e9n\u00e9ralement indiqu\u00e9e dans le tableau suivant <strong>MGOe<\/strong>. En r\u00e8gle g\u00e9n\u00e9rale, un nombre plus \u00e9lev\u00e9 signifie souvent un mat\u00e9riau magn\u00e9tique plus puissant <strong>pour le m\u00eame volume d'aimant<\/strong>, mais chaque grade a une <strong>plage autoris\u00e9e<\/strong>, et non une valeur fixe unique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du point de vue de l'approvisionnement et des essais, traitez le \u201cgrade\u201d comme une bande de sp\u00e9cifications des mat\u00e9riaux, puis utilisez des essais de force de traction r\u00e9els (ou FEA) pour la d\u00e9cision de conception finale.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tableau de classement des aimants en n\u00e9odyme<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Grade<\/th><th>Gamme typique (BH)max (MGOe)<\/th><th>Temp\u00e9rature de fonctionnement maximale typique (standard)<\/th><th>Conseil pratique de s\u00e9lection<\/th><\/tr><\/thead><tbody><tr><td><strong>N35<\/strong><\/td><td>33-35<\/td><td>\u2264 80\u00b0C<\/td><td>Bonne base pour un usage g\u00e9n\u00e9ral<\/td><\/tr><tr><td><strong>N42<\/strong><\/td><td>40-42<\/td><td>\u2264 80\u00b0C<\/td><td>Meilleur \u00e9quilibre pour la plupart des mod\u00e8les<\/td><\/tr><tr><td><strong>N45<\/strong><\/td><td>43-46<\/td><td>\u2264 80\u00b0C<\/td><td>Plus de force sans passer au N52<\/td><\/tr><tr><td><strong>N52<\/strong><\/td><td>49-52<\/td><td>\u2264 80\u00b0C<\/td><td>A utiliser lorsque l'espace est restreint et que la force maximale est importante<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Note sur le monde r\u00e9el :<\/strong> Ce graphique compare <strong>qualit\u00e9s d'aimants en n\u00e9odyme<\/strong> par leur r\u00e9sistance mat\u00e9rielle. Si votre produit fonctionne \u00e0 une temp\u00e9rature sup\u00e9rieure \u00e0 ~60-70\u00b0C, ne vous contentez pas de passer au N52. <strong>grade de temp\u00e9rature de l'aimant<\/strong> (par exemple, H\/SH\/UH\/EH\/AH) pour \u00e9viter une perte irr\u00e9versible.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/osenc.com\/wp-content\/uploads\/2025\/07\/N42-Vs-N45-Vs-N52-magnet1.webp\" alt=\"N42 Vs N45 Vs N52 magnet2\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Comment choisir la bonne qualit\u00e9 d'aimant n\u00e9odyme pour votre application ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lors du choix de la bonne qualit\u00e9 d'aimant, il est essentiel d'adapter la qualit\u00e9 \u00e0 votre application. Par exemple, si l'espace est restreint, <strong>N52<\/strong> est le meilleur choix car il offre une r\u00e9sistance maximale sous une forme compacte. Toutefois, pour un usage g\u00e9n\u00e9ral, <strong>N35<\/strong> ou <strong>N42<\/strong> peut s'av\u00e9rer plus appropri\u00e9. En cas de temp\u00e9ratures \u00e9lev\u00e9es, veillez \u00e0 s\u00e9lectionner un <strong>grade de temp\u00e9rature de l'aimant<\/strong> comme <strong>N42H<\/strong> ou <strong>N52H<\/strong>, qui offre une plus grande r\u00e9sistance \u00e0 la d\u00e9magn\u00e9tisation irr\u00e9versible.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Votre candidature<\/strong><\/th><th><strong>Classe d'aimant recommand\u00e9e<\/strong><\/th><th><strong>Pourquoi<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Utilisation standard, pas de chaleur<\/td><td>N35, N42<\/td><td>Rentable, bon rapport r\u00e9sistance\/taille<\/td><\/tr><tr><td>Faible encombrement, grande r\u00e9sistance<\/td><td>N52<\/td><td>Maximise la r\u00e9sistance dans les espaces restreints<\/td><\/tr><tr><td>Environnement \u00e0 haute temp\u00e9rature<\/td><td>N42H, N52H<\/td><td>La stabilit\u00e9 de la temp\u00e9rature est essentielle<\/td><\/tr><tr><td>Chaleur et espace mod\u00e9r\u00e9s<\/td><td>N45, N50<\/td><td>R\u00e9sistance et taille \u00e9quilibr\u00e9es pour la plupart des applications<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si<\/strong> l'espace est restreint \u2192 <strong>choisir N48-N56<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si<\/strong> l'entrefer existe \u2192 <strong>r\u00e9duire l'\u00e9cart en premier lieu \/ augmenter la surface de contact<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si<\/strong> la temp\u00e9rature est incertaine \u2192 <strong>passer au grade sup\u00e9rieur (M\/H\/SH\/UH\/EH\/AH)<\/strong> et l'\u00e9chantillon de test.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment lire un tableau de classement des aimants en n\u00e9odyme ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous comparez les qualit\u00e9s des aimants en n\u00e9odyme (ou de tout autre aimant en <strong>tableau des classes d'aimants<\/strong>), ces trois valeurs sont les plus importantes :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1) (BH)max (produit \u00e9nerg\u00e9tique maximal, MGOe)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C'est la valeur cl\u00e9 derri\u00e8re <strong>Nxx<\/strong> grades. Une valeur (BH)max plus \u00e9lev\u00e9e signifie g\u00e9n\u00e9ralement que le mat\u00e9riau NdFeB peut fournir plus d'\u00e9nergie magn\u00e9tique. <strong>par unit\u00e9 de volume<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2) Br (r\u00e9manence, g\u00e9n\u00e9ralement en Tesla ou Gauss)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Br refl\u00e8te la densit\u00e9 de flux magn\u00e9tique que le mat\u00e9riau peut produire \u00e0 pleine magn\u00e9tisation. Dans la pratique, un Br \u00e9lev\u00e9 est souvent corr\u00e9l\u00e9 \u00e0 des tendances de champ de surface plus fortes (toutes choses \u00e9gales par ailleurs).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3) Hcj (coercitivit\u00e9 intrins\u00e8que, kOe ou kA\/m)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hcj montre une r\u00e9sistance \u00e0 la d\u00e9magn\u00e9tisation, ce qui est particuli\u00e8rement important dans les cas suivants <strong>la chaleur, les vibrations et les champs magn\u00e9tiques oppos\u00e9s<\/strong>. Dans les assemblages r\u00e9els (moteurs, haut-parleurs, m\u00e9canismes compacts), la coercivit\u00e9 est souvent la limite cach\u00e9e, et non l'indice de qualit\u00e9 qui fait la une.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Conseil pratique : m\u00eame un <strong>0,2-1,0 mm d'entrefer<\/strong> (peinture, placage, ruban adh\u00e9sif, <a href=\"https:\/\/osenc.com\/fr\/rubber-coated-magnet\/\" target=\"_blank\" rel=\"noreferrer noopener\">tampons en caoutchouc<\/a>, La force de traction peut \u00eatre r\u00e9duite de plus de quelques \u00e9chelons de grade. C'est la raison pour laquelle je r\u00e9sous g\u00e9n\u00e9ralement le probl\u00e8me du \u201cpas assez fort\u201d en proc\u00e9dant comme suit <strong>r\u00e9duction de l'\u00e9cart ou augmentation de la surface de contact<\/strong> avant de payer pour une qualit\u00e9 sup\u00e9rieure.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">N45 vs N52 : Quelle est la diff\u00e9rence ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque l'on compare les aimants N45 et N52, la principale diff\u00e9rence est leur plage (BH)max. L'aimant N45 se situe g\u00e9n\u00e9ralement entre 43 et 46 MGOe, tandis que l'aimant N52 se situe entre 49 et 52 MGOe. Les aimants N52 ont tendance \u00e0 \u00eatre plus puissants \u00e0 taille et forme \u00e9gales, mais un aimant N45 plus grand peut \u00eatre plus performant qu'un N52 plus petit si le volume est augment\u00e9. Tenez toujours compte de la qualit\u00e9 de l'aimant et des conditions de contact lorsque vous faites votre choix final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D'apr\u00e8s mon exp\u00e9rience, je ne pousse que pour <a href=\"https:\/\/osenc.com\/fr\/n52-neodymium-magnets\/\" target=\"_blank\" rel=\"noreferrer noopener\">N52<\/a> quand <strong>l'espace est vraiment r\u00e9duit<\/strong> ou lorsque je ne peux pas modifier la g\u00e9om\u00e9trie. Si vous pouvez augmenter l\u00e9g\u00e8rement la taille, un <strong>Aimant N45 avec plus de volume<\/strong> peut \u00eatre plus performant qu'un petit N52 (et il peut \u00eatre plus facile de s'approvisionner r\u00e9guli\u00e8rement en production de masse).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conseil pratique d'achat : lorsque vous comparez le N45 au N52, regardez toujours les \u00e9l\u00e9ments suivants <strong>votre condition de contact r\u00e9elle<\/strong>-Si vous avez de la peinture, du placage, du caoutchouc ou une petite distance de s\u00e9paration, votre \u201cgain\u201d de N52 peut \u00eatre plus faible que pr\u00e9vu. (Voir aussi : <a href=\"https:\/\/osenc.com\/fr\/n35-vs-n52-magnet\/\" target=\"_blank\" rel=\"noopener\">aimant n35 vs n52<\/a>, <a href=\"https:\/\/osenc.com\/fr\/n42-vs-n45-vs-n52-magnet\/\" target=\"_blank\" rel=\"noopener\">aimants n45 vs n52<\/a>)<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/osenc.com\/wp-content\/uploads\/2022\/11\/maximum-energy.webp\" alt=\"\u00e9nergie maximale\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Aimants N50 vs N52<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Grade <strong>N50<\/strong> ont une force nominale l\u00e9g\u00e8rement inf\u00e9rieure \u00e0 celle des aimants <strong>N52<\/strong>, tombant g\u00e9n\u00e9ralement dans la cat\u00e9gorie des <strong>47-51 MGOe<\/strong> gamme. Dans la production r\u00e9elle, l'extr\u00e9mit\u00e9 sup\u00e9rieure de N50 peut chevaucher l'extr\u00e9mit\u00e9 inf\u00e9rieure de N52 parce que les grades sont <strong>gammes<\/strong>, et non des num\u00e9ros uniques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez besoin des \u201cmeilleures performances\u201d les plus constantes dans un design compact, le N52 est g\u00e9n\u00e9ralement le choix le plus s\u00fbr. Mais dans le domaine des achats, j'ai \u00e9galement vu des projets choisir le N50 lorsque la disponibilit\u00e9 et le co\u00fbt \u00e9taient meilleurs, puis confirmer la performance avec le N52. <strong>test d'\u00e9chantillons<\/strong> dans les conditions r\u00e9elles d'entrefer et d'acier.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/osenc.com\/wp-content\/uploads\/2022\/11\/the-power-of-different-grade.webp\" alt=\"puissance des aimants de diff\u00e9rentes qualit\u00e9s\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Comment la qualit\u00e9 de l'aimant affecte-t-elle sa force ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les performances de l'aimant d\u00e9pendent de plusieurs facteurs<strong>la taille, la forme, l'entrefer, l'\u00e9paisseur du rev\u00eatement et la surface de l'acier<\/strong> les contacts de l'aimant - et pas seulement la qualit\u00e9. Le grade est important car il refl\u00e8te la r\u00e9sistance du mat\u00e9riau NdFeB, mais il n'a pas d'incidence sur la qualit\u00e9 de l'aimant. <strong>n'\u00e9quivaut pas automatiquement \u00e0 une force de retenue r\u00e9elle<\/strong> dans votre demande.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour deux aimants de m\u00eame taille et de m\u00eame forme, des qualit\u00e9s diff\u00e9rentes peuvent apporter une am\u00e9lioration d'environ <strong>10-20%<\/strong> sous <strong>conditions id\u00e9ales pour le test de traction<\/strong> (plaque d'acier \u00e9paisse et propre, entrefer proche de z\u00e9ro). Dans les assemblages r\u00e9els, l'\u00e9cart de performance se r\u00e9duit souvent une fois que l'on introduit <strong>peinture, placage, tampons en caoutchouc, surfaces rugueuses, acier mince ou m\u00eame une petite pi\u00e8ce d\u00e9tach\u00e9e.<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J'utilise une approche d'ing\u00e9nierie pratique : si la conception le permet, il faut d'abord essayer de r\u00e9duire l'entrefer ou d'augmenter la surface de contact ; ce n'est qu'ensuite que l'on peut am\u00e9liorer la qualit\u00e9. C'est \u00e9galement la raison pour laquelle un N45 plus grand peut facilement tirer plus fort qu'un N52 plus petit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En rapport : <a href=\"https:\/\/osenc.com\/fr\/how-strong-is-a-neodymium-magnet\/\" target=\"_blank\" rel=\"noopener\">Quelle est la force des aimants en n\u00e9odyme ?<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/osenc.com\/wp-content\/uploads\/2022\/11\/force-of-differen-grade-NdFeB-magnet-1.webp\" alt=\"force d&#039;attraction d&#039;aimants de diff\u00e9rentes qualit\u00e9s\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Force de traction vs force de cisaillement (Pourquoi votre aimant glisse)<\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Force de traction et force de cisaillement : Principales diff\u00e9rences<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Force de traction<\/strong>: La force de traction verticale, g\u00e9n\u00e9ralement plus forte.<\/li>\n\n\n\n<li><strong>Force de cisaillement<\/strong>: La force de glissement lat\u00e9rale, g\u00e9n\u00e9ralement plus faible.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>La force de cisaillement est fortement influenc\u00e9e par le frottement de surface<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>\u00c9tat de surface<\/strong>: Les surfaces rugueuses, enduites ou recouvertes de caoutchouc peuvent augmenter consid\u00e9rablement le frottement, r\u00e9duisant ainsi la capacit\u00e9 de glissement.<\/li>\n\n\n\n<li><strong>Solution<\/strong>: Vous pouvez am\u00e9liorer les performances en augmentant la surface de contact, en ajoutant de la friction ou en utilisant des but\u00e9es m\u00e9caniques.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Exemple : Applications dans le monde r\u00e9el<\/strong>\n<ul class=\"wp-block-list\">\n<li>Dans la pratique, si un <strong>l'aimant est mont\u00e9 sur une surface rugueuse<\/strong>, le <strong>la force de cisaillement est g\u00e9n\u00e9ralement inf\u00e9rieure \u00e0 30%-50%<\/strong> que la force de traction.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Force de traction ou pente : pourquoi les conditions d'essai changent tout<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Configuration typique d'un test de force de traction (ce que la plupart des fournisseurs utilisent)<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u00c9paisseur de la t\u00f4le d'acier<\/strong><br>La plupart des fournisseurs utilisent <strong>plaques d'acier standard<\/strong>, L'\u00e9paisseur de la plaque d'acier est g\u00e9n\u00e9ralement de 5 \u00e0 10 mm. L'\u00e9paisseur de la plaque d'acier influe sur la <strong><a href=\"https:\/\/osenc.com\/fr\/pot-magnets\/\">force de traction<\/a> force d'essai<\/strong>, La surface de contact entre l'aimant et la surface d'acier est modifi\u00e9e.<\/li>\n\n\n\n<li><strong>\u00c9tat de surface de l'acier<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Surface lisse en acier<\/strong>: G\u00e9n\u00e8re une force de contact plus \u00e9lev\u00e9e.<\/li>\n\n\n\n<li><strong>Surface rugueuse de l'acier<\/strong>: Augmente la friction et r\u00e9duit la force de traction.<\/li>\n\n\n\n<li><strong>Rev\u00eatements\/peinture<\/strong>: Les rev\u00eatements ou les couches peintes peuvent introduire des espaces d'air, ce qui r\u00e9duit la force de traction.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Entrefer (0, 0,2, 0,5, 1,0 mm)<\/strong><br><strong>Entrefer<\/strong> est un facteur cl\u00e9 qui influe sur la <strong>force de traction<\/strong>. M\u00eame un petit entrefer (0,2 mm) peut r\u00e9duire de mani\u00e8re significative la force d'attraction r\u00e9elle d'un aimant. Les rev\u00eatements, les peintures ou les tampons en caoutchouc sont des exemples courants d'entrefers.<\/li>\n\n\n\n<li><strong>Zone de contact et alignement<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Plus grande surface de contact<\/strong> augmente la force de traction, en particulier lorsque l'aimant a une plus grande surface de contact avec la surface en acier.<\/li>\n\n\n\n<li><strong>Alignement<\/strong>: L'alignement parfait de l'aimant avec la surface en acier est un autre facteur qui influence la force de traction. Un mauvais alignement r\u00e9duit la force de traction.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Direction de traction (verticale ou cisaillement)<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Traction verticale<\/strong>: La m\u00e9thode d'essai la plus courante, o\u00f9 l'aimant est tir\u00e9 directement vers le haut \u00e0 partir de la surface de l'acier.<\/li>\n\n\n\n<li><strong>Effort de cisaillement<\/strong>: Lorsque l'aimant n'est pas tir\u00e9 verticalement, la force de cisaillement est g\u00e9n\u00e9ralement plus faible car le frottement et la zone de contact ne sont pas optimis\u00e9s.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Ce qu'il faut confirmer aupr\u00e8s de votre fournisseur :<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Demander aux fournisseurs de fournir les conditions d'essai de la force de traction<\/strong> (y compris l'\u00e9tat de la surface de l'acier, l'entrefer, la direction de traction, etc.).<br>Lors de l'achat d'aimants, demandez des <strong>conditions d'essai<\/strong> de vos fournisseurs, tels que l'\u00e9paisseur de la plaque d'acier, l'\u00e9tat de surface, la pr\u00e9sence \u00e9ventuelle d'un rev\u00eatement et le sens de traction pendant l'essai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Confirmez les donn\u00e9es d'essai du fournisseur pour vous assurer qu'elles correspondent \u00e0 vos conditions r\u00e9elles.<\/strong><br>Vous pouvez demander au fournisseur <strong>donn\u00e9es d'essai de la force de traction dans le monde r\u00e9el<\/strong> et r\u00e9aliser <strong>validation de la demande<\/strong>. Par exemple, si votre application implique des rev\u00eatements ou des surfaces rugueuses, demandez au fournisseur les donn\u00e9es d'essai pertinentes pour v\u00e9rifier la force de traction de l'aimant dans ces conditions.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tous les aimants utilisent-ils le m\u00eame syst\u00e8me de notation ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Non. <strong>Ferrite, <a href=\"https:\/\/osenc.com\/fr\/smco-magnet\/\">SmCo<\/a>, et les aimants NdFeB (n\u00e9odyme) ne partagent pas le m\u00eame syst\u00e8me de classification.<\/strong> \u201cLes \u201dgrades d'aimants\" d\u00e9pendent de la famille de mat\u00e9riaux et des normes utilis\u00e9es. <strong>(BH)max, coercivit\u00e9, r\u00e9manence et stabilit\u00e9 \u00e0 la temp\u00e9rature<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour le NdFeB (<strong>Cat\u00e9gories d'aimants NdFeB<\/strong>), des notes comme <strong>N35 \/ N42 \/ N52<\/strong> sont li\u00e9es principalement \u00e0 <strong>(BH)max<\/strong>, Les qualit\u00e9s sup\u00e9rieures sont donc g\u00e9n\u00e9ralement synonymes de mat\u00e9riaux plus r\u00e9sistants. Pour le SmCo (un autre <strong>aimant en terre rare<\/strong>), le classement tend \u00e0 mettre l'accent sur les <strong>stabilit\u00e9 \u00e0 haute temp\u00e9rature et coercivit\u00e9<\/strong>. Pour la ferrite, la d\u00e9nomination de la qualit\u00e9 diff\u00e8re et se concentre souvent sur les propri\u00e9t\u00e9s au sein de sa propre norme.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/osenc.com\/wp-content\/uploads\/2022\/11\/magnet-type-comparison.webp\" alt=\"comparaison des types d&#039;aimants\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En mati\u00e8re d'approvisionnement, l'approche la plus s\u00fbre consiste \u00e0 partir des exigences de votre application (temp\u00e9rature, environnement, limites de taille, force de traction cible), puis \u00e0 choisir le type et la qualit\u00e9 d'aimant qui conviennent - plut\u00f4t que d'imposer une approche \u201cunique\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/osenc.com\/wp-content\/uploads\/2022\/11\/ferrite-and-neodymium-magnet-compare.webp\" alt=\"comparaison des aimants en ferrite et en n\u00e9odyme\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">NdFeB vs SmCo vs Ferrite : Quelle famille d'aimants choisir ?<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Mat\u00e9riau<\/strong><\/th><th><strong>R\u00e9sistance (typique)<\/strong><\/th><th><strong>R\u00e9sistance \u00e0 la temp\u00e9rature<\/strong><\/th><th><strong>R\u00e9sistance \u00e0 la corrosion<\/strong><\/th><th><strong>Co\u00fbt<\/strong><\/th><th><strong>Applications les mieux adapt\u00e9es<\/strong><\/th><\/tr><\/thead><tbody><tr><td><strong>NdFeB (N\u00e9odyme)<\/strong><\/td><td>Haut<\/td><td>Mod\u00e9r\u00e9 (80-230\u00b0C)<\/td><td>Faible (n\u00e9cessite un rev\u00eatement)<\/td><td>Mod\u00e9r\u00e9<\/td><td>Des espaces compacts et performants<\/td><\/tr><tr><td><strong>SmCo (Samarium Cobalt)<\/strong><\/td><td>Haut<\/td><td>Tr\u00e8s \u00e9lev\u00e9 (jusqu'\u00e0 350\u00b0C)<\/td><td>Haut<\/td><td>Haut<\/td><td>Applications \u00e0 haute temp\u00e9rature, a\u00e9rospatiale<\/td><\/tr><tr><td><strong>Ferrite (c\u00e9ramique)<\/strong><\/td><td>Mod\u00e9r\u00e9<\/td><td>Mod\u00e9r\u00e9 (jusqu'\u00e0 250\u00b0C)<\/td><td>Mod\u00e9r\u00e9<\/td><td>Faible<\/td><td>Applications \u00e9conomiques \u00e0 faible consommation d'\u00e9nergie<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Lettres suppl\u00e9mentaires sur les grades des aimants en n\u00e9odyme<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Parfois, les grades d'aimants en n\u00e9odyme comprennent des lettres suppl\u00e9mentaires \u00e0 la fin (par exemple : <strong>N42H, N42SH, N42UH<\/strong>). Ces lettres indiquent principalement <strong>r\u00e9sistance \u00e0 la temp\u00e9rature<\/strong>-La capacit\u00e9 de l'aimant \u00e0 supporter la chaleur sans subir de d\u00e9magn\u00e9tisation irr\u00e9versible. Les aimants NdFeB standard sont g\u00e9n\u00e9ralement \u00e9valu\u00e9s pour <strong>\u2264 80\u00b0C<\/strong>, Mais la \u201ctemp\u00e9rature ambiante\u201d n'est souvent pas la r\u00e9alit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans les applications r\u00e9elles, la temp\u00e9rature est l'un des facteurs cach\u00e9s les plus courants. J'ai vu des aimants qui semblaient parfaits lors des tests de traction \u00e0 temp\u00e9rature ambiante perdre rapidement de leur force une fois install\u00e9s \u00e0 proximit\u00e9 d'une source d'\u00e9nergie. <strong>les stators de moteurs, les composants de freins, les appareils de chauffage ou les bo\u00eetiers ferm\u00e9s<\/strong> o\u00f9 la chaleur s'accumule et ne peut s'\u00e9chapper. Si votre projet est expos\u00e9 \u00e0 une chaleur inconnue, le choix de la bonne solution d'isolation thermique peut s'av\u00e9rer utile. <strong>grade de temp\u00e9rature de l'aimant<\/strong> est souvent plus importante que la recherche du nombre N le plus \u00e9lev\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\ud83c\udf21\ufe0f Classes de temp\u00e9rature des aimants en n\u00e9odyme (lettres suffixes)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les aimants NdFeB standard sont g\u00e9n\u00e9ralement pr\u00e9vus pour une temp\u00e9rature \u2264 80\u00b0C.<\/strong> Si votre application fonctionne \u00e0 chaud (moteurs, bo\u00eetiers ferm\u00e9s, \u00e0 proximit\u00e9 d'appareils de chauffage), choisissez un grade avec suffixe de temp\u00e9rature.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Suffixe<\/th><th>Temp\u00e9ratures de fonctionnement maximales typiques<\/th><th>Quand utiliser<\/th><\/tr><\/thead><tbody><tr><td><strong>M<\/strong><\/td><td>\u2264 100\u00b0C<\/td><td>Chaleur l\u00e9g\u00e8re, marge de s\u00e9curit\u00e9 de base<\/td><\/tr><tr><td><strong>H<\/strong><\/td><td>\u2264 120\u00b0C<\/td><td>Environnements chauds \u00e0 proximit\u00e9 des moteurs\/appareils \u00e9lectrom\u00e9nagers<\/td><\/tr><tr><td><strong>SH<\/strong><\/td><td>\u2264 150\u00b0C<\/td><td>Chaleur plus \u00e9lev\u00e9e, \u00e9quipement ferm\u00e9, fonctionnement r\u00e9gulier<\/td><\/tr><tr><td><strong>UH<\/strong><\/td><td>\u2264 180\u00b0C<\/td><td>Conditions industrielles \u00e0 haute temp\u00e9rature<\/td><\/tr><tr><td><strong>EH<\/strong><\/td><td>\u2264 200\u00b0C<\/td><td>Chaleur tr\u00e8s \u00e9lev\u00e9e, n\u00e9cessit\u00e9 d'une r\u00e9sistance rigoureuse au d\u00e9magage<\/td><\/tr><tr><td><strong>AH<\/strong><\/td><td>\u2264 230\u00b0C<\/td><td>Chaleur extr\u00eame ; v\u00e9rifier par la fiche technique\/l'essai<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>R\u00e8gle pratique que j'utilise :<\/strong> si l'aimant se trouve \u00e0 proximit\u00e9 d'une source de chaleur et que vous n'\u00eates pas s\u00fbr de la temp\u00e9rature maximale r\u00e9elle, augmentez au moins la temp\u00e9rature de l'aimant. <strong>une classe de temp\u00e9rature<\/strong> (par exemple : de standard \u00e0 H, ou de H \u00e0 SH) et valider avec un test d'\u00e9chantillonnage rapide.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Note : les limites de temp\u00e9rature sont des indications typiques de l'industrie. Confirmez toujours avec la fiche technique de votre fournisseur et testez si l'application est critique.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/osenc.com\/wp-content\/uploads\/2022\/11\/temperature-of-magnet.webp\" alt=\"temp\u00e9rature de l&#039;aimant n\u00e9odyme\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Que signifie l'expression \u201ctemp\u00e9rature maximale de fonctionnement\u201d ?<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Temp\u00e9rature de fonctionnement et d\u00e9faillance de l'aimant :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La classe de temp\u00e9rature (M\/H\/SH\/UH\/EH\/AH) indique le degr\u00e9 de r\u00e9sistance de l'aimant. <strong>temp\u00e9rature maximale de fonctionnement<\/strong> sur des p\u00e9riodes prolong\u00e9es, <strong>pas<\/strong> sa temp\u00e9rature maximale.<\/li>\n\n\n\n<li><strong>Temp\u00e9rature de fonctionnement continu<\/strong>: Temp\u00e9rature maximale que l'aimant peut supporter en fonctionnement continu.<\/li>\n\n\n\n<li><strong>Temp\u00e9rature maximale<\/strong>: La temp\u00e9rature maximale que l'aimant peut supporter pendant de courtes p\u00e9riodes avant de subir une d\u00e9magn\u00e9tisation irr\u00e9versible.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Comment \u00e9viter une s\u00e9lection incorrecte de la classe de temp\u00e9rature :<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si l'aimant est situ\u00e9 \u00e0 proximit\u00e9 d'une source de chaleur (comme les moteurs, les appareils de chauffage ou les \u00e9quipements ferm\u00e9s), <strong>la temp\u00e9rature ambiante peut \u00eatre sup\u00e9rieure de 20 \u00e0 40\u00b0C \u00e0 la temp\u00e9rature r\u00e9elle de la surface<\/strong> de l'aimant.<\/li>\n\n\n\n<li>Lorsque l'on s\u00e9lectionne l'option <strong>classe de temp\u00e9rature<\/strong>, il est conseill\u00e9 de choisir un grade <strong>un niveau plus \u00e9lev\u00e9<\/strong> en cas de doute sur les conditions de temp\u00e9rature. Si possible, effectuez des tests sur des \u00e9chantillons pour confirmer.<\/li>\n<\/ul>\n\n\n\n<ol class=\"wp-block-list\">\n<li><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Sp\u00e9cifications des aimants (tableau de r\u00e9f\u00e9rence pour les qualit\u00e9s d'aimants NdFeB)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouverez ci-dessous un tableau de r\u00e9f\u00e9rence indiquant les fourchettes typiques de propri\u00e9t\u00e9s pour les biens communs. <strong>Cat\u00e9gories d'aimants NdFeB<\/strong>. Lorsque les ing\u00e9nieurs utilisent un <strong>tableau des qualit\u00e9s des aimants en n\u00e9odyme<\/strong>, Les colonnes les plus pratiques sont les suivantes <strong>Br<\/strong> (r\u00e9manence), <strong>Hcj<\/strong> (coercivit\u00e9 intrins\u00e8que), et <strong>(BH)max<\/strong> (produit \u00e9nerg\u00e9tique).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comment j'utilise ce tableau dans des projets r\u00e9els :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Utilisation <strong>(BH)max<\/strong> pour comparer les bandes de r\u00e9sistance de grade (N35 vs N42 vs N52).<\/li>\n\n\n\n<li>V\u00e9rifier <strong>Hcj<\/strong> s'il y a de la chaleur, des vibrations ou des champs oppos\u00e9s (c'est l\u00e0 que le suffixe de temp\u00e9rature a de l'importance).<\/li>\n\n\n\n<li>Traiter toutes les valeurs comme <strong>gammes<\/strong> et confirmez avec la fiche technique d'un fournisseur pour le syst\u00e8me de lot\/mat\u00e9riau exact.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><th rowspan=\"3\">\n<p>Mat\u00e9riau<br>magn\u00e9tisation<br>grade<\/p>\n<\/th><th colspan=\"2\">R\u00e9manence<\/th><th colspan=\"4\">Coercivit\u00e9<\/th><th colspan=\"2\">\u00c9nergie<br>produit<\/th><th rowspan=\"2\">Max.<br>Temp\u00e9rature<\/th><\/tr><tr><th colspan=\"2\">Br<\/th><th colspan=\"2\">bHc<\/th><th colspan=\"2\">iHc<\/th><th colspan=\"2\">(BxH)max<\/th><\/tr><tr><th>Gauss (G)<\/th><th>Tesla (T)<\/th><th>kOe<\/th><th>k\/m<\/th><th>kOe<\/th><th>k\/m<\/th><th>MGOe<\/th><th>kJ\/m\u00b3<\/th><th>\u00b0C<\/th><\/tr><tr><td>N30<\/td><td>10800-11200<\/td><td>1.08-1.12<\/td><td>9.8-10.5<\/td><td>780-836<\/td><td>\u2265 12<\/td><td>\u2265 955<\/td><td>28-30<\/td><td>223-239<\/td><td>\u2264 80<\/td><\/tr><tr><td>N33<\/td><td>11400-11700<\/td><td>1.14-1.17<\/td><td>10.3-11.0<\/td><td>820-876<\/td><td>\u2265 12<\/td><td>\u2265 955<\/td><td>31-33<\/td><td>247-263<\/td><td>\u2264 80<\/td><\/tr><tr><td>N35<\/td><td>11700-12100<\/td><td>1.17-1.21<\/td><td>10.8-11.5<\/td><td>860-915<\/td><td>\u2265 12<\/td><td>\u2265 955<\/td><td>33-35<\/td><td>263-279<\/td><td>\u2264 80<\/td><\/tr><tr><td>N38<\/td><td>12200-12600<\/td><td>1.22-1.26<\/td><td>10.8-11.5<\/td><td>860-915<\/td><td>\u2265 12<\/td><td>\u2265 955<\/td><td>36-38<\/td><td>287-303<\/td><td>\u2264 80<\/td><\/tr><tr><td>N40<\/td><td>12600-12900<\/td><td>1.26-1.29<\/td><td>10.5-12.0<\/td><td>860-955<\/td><td>\u2265 12<\/td><td>\u2265 955<\/td><td>38-40<\/td><td>303-318<\/td><td>\u2264 80<\/td><\/tr><tr><td>N42<\/td><td>12900-13200<\/td><td>1.29-1.32<\/td><td>10.8-12.0<\/td><td>860-955<\/td><td>\u2265 12<\/td><td>\u2265 955<\/td><td>40-42<\/td><td>318-334<\/td><td>\u2264 80<\/td><\/tr><tr><td>N45<\/td><td>13200-13700<\/td><td>1.32-1.37<\/td><td>10.8-12.5<\/td><td>860-995<\/td><td>\u2265 12<\/td><td>\u2265 955<\/td><td>43-45<\/td><td>342-358<\/td><td>\u2264 80<\/td><\/tr><tr><td>N48<\/td><td>13700-14200<\/td><td>1.37-1.42<\/td><td>10.8-12.5<\/td><td>860-995<\/td><td>\u2265 12<\/td><td>\u2265 955<\/td><td>45-48<\/td><td>358-382<\/td><td>\u2264 80<\/td><\/tr><tr><td>N50<\/td><td>14000-14600<\/td><td>1.40-1.46<\/td><td>10.8-12.5<\/td><td>860-995<\/td><td>\u2265 12<\/td><td>\u2265 955<\/td><td>47-51<\/td><td>374-406<\/td><td>\u2264 80<\/td><\/tr><tr><td>N52<\/td><td>14200-14700<\/td><td>1.42-1.47<\/td><td>10.8-12.5<\/td><td>860-995<\/td><td>\u2265 12<\/td><td>\u2265 955<\/td><td>48-53<\/td><td>380-422<\/td><td>\u2264 80<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La qualit\u00e9 d'un aimant est un indicateur crucial de la performance du mat\u00e9riau NdFeB, mais ce n'est pas le seul facteur qui d\u00e9termine la force de r\u00e9tention r\u00e9elle. Lorsque vous choisissez un aimant en n\u00e9odyme, je vous recommande de commencer par la qualit\u00e9 comme base de r\u00e9f\u00e9rence (en utilisant un <strong>tableau des classes d'aimants<\/strong>), puis en v\u00e9rifiant la performance finale sur la base de <strong>taille\/forme de l'aimant, entrefer, <a href=\"https:\/\/osenc.com\/fr\/neodymium-magnet-coating\/\">\u00e9paisseur du rev\u00eatement<\/a>, et l'\u00e9tat de surface de l'acier<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les aimants en n\u00e9odyme sont g\u00e9n\u00e9ralement beaucoup plus r\u00e9sistants que les aimants en ferrite, et le num\u00e9ro du grade renvoie \u00e0 la qualit\u00e9 de l'aimant. <strong>Gamme (BH)max en MGOe<\/strong>. Enfin, les lettres suffixes de temp\u00e9rature (<strong>M\/H\/SH\/UH\/EH\/AH<\/strong>) ont une grande importance dans les \u00e9quipements r\u00e9els - si l'exposition \u00e0 la temp\u00e9rature est incertaine, le choix de la bonne <strong>grade de temp\u00e9rature de l'aimant<\/strong> (ou tester un \u00e9chantillon dans des conditions r\u00e9elles) est g\u00e9n\u00e9ralement le moyen le plus rapide d'\u00e9viter des surprises ult\u00e9rieures en mati\u00e8re de performances.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">FAQ<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Aimant n\u00e9odyme n52 force<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"\/fr\/n52-neodymium-magnets\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aimants en n\u00e9odyme N52<\/a> se situent g\u00e9n\u00e9ralement dans la cat\u00e9gorie des <strong>49-52 MGOe<\/strong> pour un maximum d'\u00e9nergie. Dans la pratique, le N52 est l'un des carburants les plus \u00e9lev\u00e9s couramment disponibles. <strong>qualit\u00e9s d'aimants en n\u00e9odyme<\/strong>, mais la force de maintien r\u00e9elle d\u00e9pend encore fortement de la taille de l'aimant, de sa forme, de l'entrefer et de l'\u00e9tat de la surface de l'acier utilis\u00e9 pour les essais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Comment les aimants sont-ils \u00e9valu\u00e9s ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les aimants sont g\u00e9n\u00e9ralement class\u00e9s par <strong>type de mat\u00e9riau<\/strong>, <strong>grade<\/strong>et <strong>performance mesur\u00e9e<\/strong>. Pour le NdFeB (<strong>Cat\u00e9gories d'aimants NdFeB<\/strong>), le grade (N35, N42, N52) concerne principalement <strong>(BH)max<\/strong>, Les qualit\u00e9s sup\u00e9rieures indiquent donc g\u00e9n\u00e9ralement un mat\u00e9riau magn\u00e9tique plus puissant <strong>au m\u00eame volume<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La force de retenue r\u00e9elle est g\u00e9n\u00e9ralement indiqu\u00e9e comme suit <strong>force de traction<\/strong>, mais ce chiffre d\u00e9pend fortement des conditions d'essai (\u00e9paisseur de l'acier, finition de la surface et, en particulier, espace d'air). Le champ de surface peut \u00eatre mesur\u00e9 en <strong>Gauss<\/strong>, L'indice de temp\u00e9rature est important car le NdFeB peut perdre de sa r\u00e9sistance s'il est surchauff\u00e9 - c'est la raison pour laquelle le NdFeB doit \u00eatre utilis\u00e9 dans des conditions normales. <strong>degr\u00e9s de temp\u00e9rature de l'aimant<\/strong> (H\/SH\/UH\/EH\/AH) sont importantes dans de nombreuses applications. Lors des achats, je demande toujours les conditions d'essai du fournisseur pour la force de traction, car un \u201cm\u00eame aimant\u201d peut \u00eatre tr\u00e8s diff\u00e9rent selon les installations d'essai.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Signification de l'aimant N52<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un aimant N52 est un aimant en n\u00e9odyme (NdFeB) de haute qualit\u00e9. Le \u201c52\u201d renvoie \u00e0 son <strong>(BH)max (environ 49-52 MGOe)<\/strong>, C'est la raison pour laquelle il figure en t\u00eate de la plupart des listes de candidats \u00e0 l'adh\u00e9sion \u00e0 l'UE. <strong>diagrammes des qualit\u00e9s d'aimants en n\u00e9odyme<\/strong>. En g\u00e9n\u00e9ral, un grade sup\u00e9rieur offre des performances mat\u00e9rielles plus \u00e9lev\u00e9es, mais la force de r\u00e9tention r\u00e9elle d\u00e9pend toujours de la taille et de la forme de l'aimant, ainsi que des conditions de contact dans votre application - en particulier l'entrefer et la surface de l'acier.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelle est la meilleure qualit\u00e9 d'aimant n\u00e9odyme pour la plupart des applications ?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>N52 est le meilleur pour les applications \u00e0 haute performance<\/strong> en raison de sa r\u00e9sistance sup\u00e9rieure. Cependant, <strong>N42 et N35<\/strong> sont souvent suffisants pour des utilisations moins exigeantes, offrant un bon \u00e9quilibre entre la r\u00e9sistance, le co\u00fbt et la disponibilit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le N42SH est-il plus fort que le N52 ?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Non, le N42SH n'est pas plus r\u00e9sistant que le N52.<\/strong> N42SH fait r\u00e9f\u00e9rence au grade (N42) et \u00e0 la tol\u00e9rance \u00e0 la temp\u00e9rature (SH). N52 a une force magn\u00e9tique plus \u00e9lev\u00e9e, tandis que SH indique une r\u00e9sistance \u00e0 la chaleur jusqu'\u00e0 150\u00b0C.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pourquoi mon aimant semble-t-il plus faible apr\u00e8s l'installation ?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les aimants semblent plus faibles apr\u00e8s l'installation en raison d'espaces d'air ou d'interf\u00e9rences mat\u00e9rielles.<\/strong> Un mauvais alignement ou des mat\u00e9riaux non ferreux entre l'aimant et la surface peuvent r\u00e9duire la force effective, ce qui donne l'impression que l'aimant est moins puissant.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelle condition d'essai de force de traction dois-je comparer ?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tester la force de traction sur une surface plane et propre en acier.<\/strong> Veillez \u00e0 ce qu'il n'y ait pas d'espace, de rev\u00eatement ou de d\u00e9bris entre l'aimant et l'acier, car ces \u00e9l\u00e9ments peuvent r\u00e9duire la force mesur\u00e9e et affecter la pr\u00e9cision du test de force de traction.<\/p>","protected":false},"excerpt":{"rendered":"<p>Magnets come in various grades, especially for neodymium magnets (NdFeB). The term \u201cmagnet grades\u201d typically refers to the material&#8217;s (BH)max or maximum energy product, which is a key value for comparing the strength of neodymium magnet grades. While magnet grades are a reliable indicator of material strength, they do not directly equate to pull force, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1707,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-1698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magnet"],"_links":{"self":[{"href":"https:\/\/osenc.com\/fr\/wp-json\/wp\/v2\/posts\/1698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osenc.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osenc.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osenc.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/osenc.com\/fr\/wp-json\/wp\/v2\/comments?post=1698"}],"version-history":[{"count":0,"href":"https:\/\/osenc.com\/fr\/wp-json\/wp\/v2\/posts\/1698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osenc.com\/fr\/wp-json\/wp\/v2\/media\/1707"}],"wp:attachment":[{"href":"https:\/\/osenc.com\/fr\/wp-json\/wp\/v2\/media?parent=1698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osenc.com\/fr\/wp-json\/wp\/v2\/categories?post=1698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osenc.com\/fr\/wp-json\/wp\/v2\/tags?post=1698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}